{"id":8,"count":6,"description":"","link":"https:\/\/vallianz.co.id\/id\/category\/event\/","name":"Event","slug":"event","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/vallianz.co.id\/id\/wp-json\/wp\/v2\/categories\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vallianz.co.id\/id\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/vallianz.co.id\/id\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/vallianz.co.id\/id\/wp-json\/wp\/v2\/posts?categories=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}